{"id":5392,"date":"2026-02-22T16:29:52","date_gmt":"2026-02-22T15:29:52","guid":{"rendered":"https:\/\/conteurspro.fr\/site\/?p=5392"},"modified":"2026-02-24T13:30:31","modified_gmt":"2026-02-24T12:30:31","slug":"commission-transmission","status":"publish","type":"post","link":"https:\/\/conteurspro.fr\/site\/2026\/02\/22\/commission-transmission\/","title":{"rendered":"Commission Transmissions"},"content":{"rendered":"\n<p><strong>Bienvenue \u00e0 cette nouvelle commission !<\/strong><\/p>\n\n\n\n<p id=\"isPasted\">Cette commission est n\u00e9e lors de l\u2019AG de septembre 2025, en r\u00e9ponse aux besoins d&rsquo;\u00e9changes, exprim\u00e9s par les conteurs et conteuses qui sont dans leurs premi\u00e8res ann\u00e9es de m\u00e9tier.<\/p>\n\n\n\n<p>Elle est compos\u00e9e \u00e9galement de conteuses et conteurs de plus longue exp\u00e9rience, dans un esprit de compagnonnage.<\/p>\n\n\n\n<p>L&rsquo;id\u00e9e \u00e9tant que, \u00e0 chaque moment de son parcours, un.e artiste apporte son regard et son questionnement, ses doutes, ses convictions, ses r\u00eaves.<\/p>\n\n\n\n<p>Cette commission se veut un espace de partage, de recherche, de r\u00e9flexion autour de notre art, de ses enjeux et des mots que nous choisissons pour en parler.<\/p>\n\n\n\n<p>Nous nous proposons de d\u00e9marrer sur trois axes de travail :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Pr\u00e9voir nos chantiers, modestes ou ambitieux, caler l&rsquo;organisation pratique, penser la communication externe.<\/li>\n\n\n\n<li>Identifier nos sujets \u00ab\u00a0br\u00fblants\u00a0\u00bb, y r\u00e9fl\u00e9chir ensemble.<\/li>\n\n\n\n<li>Prendre le temps de nous nourrir des ressources pr\u00e9cieuses laiss\u00e9es par de nombreux artistes de la parole et chercheuses, chercheurs, depuis des d\u00e9cennies : <a href=\"https:\/\/5sscl.r.sp1-brevo.net\/mk\/cl\/f\/sh\/6rqJfgq8dIR6Se7um9s3aY18Quh\/OYAQULa9X-aF\" target=\"_blank\" rel=\"noreferrer noopener\">vid\u00e9os de la commission m\u00e9moire<\/a> et autres, ouvrages, conf\u00e9rences, enqu\u00eates&#8230;. afin de soutenir le d\u00e9veloppement de cet art.<\/li>\n<\/ul>\n\n\n\n<p>La commission Transmissions aimerait \u00eatre reli\u00e9e aux autres commissions. Selon l&rsquo;actualit\u00e9 et les projets, il s&rsquo;agirait de partager ses recherches, de questionner les chantiers voisins, et parfois, construire ensemble.<\/p>\n\n\n\n<p>A l&rsquo;heure de sa d\u00e9claration d&rsquo;intention, la commission rassemble dix personnes. Il y r\u00e8gne un \u00e9tat d&rsquo;esprit enthousiaste, proche de celui d&rsquo;un cuistot qui pr\u00e9pare joyeusement son buffet.&nbsp;<\/p>\n\n\n\n<p>La premi\u00e8re action de la commission s&rsquo;est d\u00e9roul\u00e9e mardi 20 janvier autour de la th\u00e9matique : \u00ab\u00a0Comment produire son spectacle de conte ?\u00a0\u00bb. Si vous n&rsquo;avez pas pu participer, un document d\u00e9taillant les \u00e9tapes de production a \u00e9t\u00e9 r\u00e9alis\u00e9, le voici :<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><a href=\"https:\/\/conteurspro.fr\/site\/wp-content\/uploads\/2026\/01\/Doc-Produire-son-spectacle-de-conte.pdf\">Premi\u00e8re action : Visio \u00ab\u00a0Comment produire son spectacle de conte ?\u00a0\u00bb<\/a><\/h4>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/conteurspro.fr\/site\/wp-content\/uploads\/2026\/01\/Doc-Produire-son-spectacle-de-conte.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Contenu embarqu\u00e9 Doc Produire son spectacle de conte.\"><\/object><a id=\"wp-block-file--media-2a59f4d0-0c14-486f-aced-829d2c2c5aab\" href=\"https:\/\/conteurspro.fr\/site\/wp-content\/uploads\/2026\/01\/Doc-Produire-son-spectacle-de-conte.pdf\">Doc Produire son spectacle de conte<\/a><a href=\"https:\/\/conteurspro.fr\/site\/wp-content\/uploads\/2026\/01\/Doc-Produire-son-spectacle-de-conte.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-2a59f4d0-0c14-486f-aced-829d2c2c5aab\">T\u00e9l\u00e9charger<\/a><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p>N&rsquo;h\u00e9sitez pas \u00e0 rejoindre la commission en nous \u00e9crivant \u00e0 &#x63;&#111;&#x6d;&#x61;p&#x61;&#99;&#64;&#x63;&#111;n&#x74;&#101;&#x75;&#x72;s&#x70;&#114;o&#x2e;&#102;r !<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bienvenue \u00e0 cette nouvelle commission ! Cette commission est n\u00e9e lors de l\u2019AG de septembre 2025, en r\u00e9ponse aux besoins d&rsquo;\u00e9changes, exprim\u00e9s par les conteurs et conteuses qui sont dans leurs premi\u00e8res ann\u00e9es de m\u00e9tier. Elle est compos\u00e9e \u00e9galement de conteuses et conteurs de plus longue exp\u00e9rience, dans un esprit de compagnonnage. L&rsquo;id\u00e9e \u00e9tant que, \u00e0 chaque moment de son parcours, un.e artiste apporte son regard et son questionnement, ses doutes, ses convictions, ses r\u00eaves. Cette commission se veut un espace de partage, de recherche, de r\u00e9flexion autour de notre art, de ses enjeux et des mots que nous choisissons pour en parler. Nous nous proposons de d\u00e9marrer sur trois axes de travail : La commission Transmissions aimerait \u00eatre reli\u00e9e aux autres commissions. Selon l&rsquo;actualit\u00e9 et les projets, il s&rsquo;agirait de partager ses recherches, de questionner les chantiers voisins, et parfois, construire ensemble. A l&rsquo;heure de sa d\u00e9claration d&rsquo;intention, la commission rassemble dix personnes. Il y r\u00e8gne un \u00e9tat d&rsquo;esprit enthousiaste, proche de celui d&rsquo;un cuistot qui pr\u00e9pare joyeusement son buffet.&nbsp; La premi\u00e8re action de la commission s&rsquo;est d\u00e9roul\u00e9e mardi 20 janvier autour de la th\u00e9matique : \u00ab\u00a0Comment produire son spectacle de conte ?\u00a0\u00bb. Si vous n&rsquo;avez pas pu participer, un document d\u00e9taillant les \u00e9tapes de production a \u00e9t\u00e9 r\u00e9alis\u00e9, le voici : Premi\u00e8re action : Visio \u00ab\u00a0Comment produire son spectacle de conte ?\u00a0\u00bb N&rsquo;h\u00e9sitez pas \u00e0 rejoindre la commission en nous \u00e9crivant \u00e0 &#x63;&#x6f;&#109;&#97;p&#x61;&#x63;&#x40;&#99;on&#x74;&#x65;&#117;&#114;s&#x70;&#x72;&#x6f;&#46;fr !<\/p>\n","protected":false},"author":23,"featured_media":5406,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-5392","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites"],"_links":{"self":[{"href":"https:\/\/conteurspro.fr\/site\/wp-json\/wp\/v2\/posts\/5392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conteurspro.fr\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conteurspro.fr\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conteurspro.fr\/site\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/conteurspro.fr\/site\/wp-json\/wp\/v2\/comments?post=5392"}],"version-history":[{"count":4,"href":"https:\/\/conteurspro.fr\/site\/wp-json\/wp\/v2\/posts\/5392\/revisions"}],"predecessor-version":[{"id":5407,"href":"https:\/\/conteurspro.fr\/site\/wp-json\/wp\/v2\/posts\/5392\/revisions\/5407"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conteurspro.fr\/site\/wp-json\/wp\/v2\/media\/5406"}],"wp:attachment":[{"href":"https:\/\/conteurspro.fr\/site\/wp-json\/wp\/v2\/media?parent=5392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conteurspro.fr\/site\/wp-json\/wp\/v2\/categories?post=5392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conteurspro.fr\/site\/wp-json\/wp\/v2\/tags?post=5392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}